{"id":11104,"date":"2025-09-02T05:06:50","date_gmt":"2025-09-02T10:06:50","guid":{"rendered":"https:\/\/www.avire-global.com\/en-us\/?post_type=division&#038;p=11104"},"modified":"2025-10-09T12:42:43","modified_gmt":"2025-10-09T17:42:43","slug":"smartview-1","status":"publish","type":"division","link":"https:\/\/www.avire-global.com\/en-us\/divisions\/elevator-safety\/two-way-voice-visual-text-communication\/smartview-1\/","title":{"rendered":"SmartView 1 (Discontinued)"},"content":{"rendered":"\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\"><div class=\"wp-block-doo-block-system-hero\">\n\t<div class=\"system-hero\">\n\t<div class=\"wp-block-columns\">\n\t\t<div class=\"wp-block-column\">\n\t\t\t<div class=\"image\">\n\t\t\t\t<img decoding=\"async\" width=\"528\" height=\"397\" src=\"https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2025\/09\/SmartView-1_Website_Image-1.png\" class=\"attachment-large size-large wp-post-image\" alt=\"\" srcset=\"https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2025\/09\/SmartView-1_Website_Image-1.png 528w, https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2025\/09\/SmartView-1_Website_Image-1-300x226.png 300w\" sizes=\"(max-width: 528px) 100vw, 528px\" \/>\t\t\t<\/div>\n\t\t<\/div>\n\t\t<div class=\"wp-block-column\">\n\t\t\t<div class=\"brands\"><img decoding=\"async\" width=\"300\" height=\"111\" src=\"https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2025\/11\/RATH-logo_full-color_no-background.svg\" class=\"attachment-medium size-medium\" alt=\"Rath\" \/><\/div>\n\t\t\t\t\t\t\t<div class=\"label\">Two-Way Voice &amp; Visual Text Communication<\/div>\n\t\t\t\t\t\t\t<h1 class=\"title\">SmartView 1 (Discontinued)<\/h1>\n\t\t\t\t\t\t\t<div class=\"label\">Compliant with<\/div>\n\t\t\t\t<div class=\"chips-link\">\n\t\t\t\t\t<div class=\"chips\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"chip\"><a href=\"https:\/\/www.avire-global.com\/en-us\/code-requirements\/?code=1780#codes\">ADA<\/a><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"chip\"><a href=\"https:\/\/www.avire-global.com\/en-us\/code-requirements\/?code=1769#codes\">ASME 17.1 (2019\/2022)<\/a><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<span class=\"chip\"><a href=\"https:\/\/www.avire-global.com\/en-us\/code-requirements\/?code=7373#codes\">CSA B44<\/a><\/span>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"doo-link\">\n\t\t\t\t\t\t\t<a href=\"https:\/\/www.avire-global.com\/en-us\/code-requirements\/\">See code information<\/a>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"wp-block-buttons\">\n\t\t\t\t\t\t\t\t\t\t<div class=\"wp-block-button  link-popup\"><a class =\"wp-block-button__link\" href=\"#contact\">Contact us<\/a><\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wp-block-button secondary popup-link-tech\"><a class =\"wp-block-button__link\" href=\"#\">Tech support<\/a><\/div>\n\t\t\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div><\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-neutral-bg-05-background-color has-background has-global-padding is-layout-constrained wp-container-core-group-is-layout-d3f30732 wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--fluid-0-56);padding-bottom:var(--wp--preset--spacing--fluid-0-56); width: 1448px;\">\n<div class=\"custom-slider-container no-items\">\n\t\t\t\t<div class=\"slider-content\">\n        \t<h2>Overview<\/h2>\n        \t<div class=\"slider-text\">\n\t\t\t\t\n<div class=\"wp-block-doo-block-system-overview alignwide\"><div class=\"gallery-content\">\n<p><strong>Attention SmartView 1 Users<\/strong><\/p>\n\n\n\n<p><br><strong>Starting January 27th, 2025, the viewing and monitoring of all SmartView 1 devices will move from&nbsp;<a href=\"http:\/\/rathsmartview.com\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">rathsmartview.com<\/a>&nbsp;to&nbsp;<a href=\"http:\/\/smartviewhub.com\/\" target=\"_blank\" rel=\"noreferrer noopener nofollow\">smartviewhub.com<\/a>.&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>All users will be required to have a SmartView Hub log in to access their SmartView 1 devices. Without a SmartView Hub account, you will be unable to access your devices for monitoring or testing purposes.&nbsp;<\/strong><\/p>\n\n\n\n<p><strong>RATH by AVIRE therefore no longer recommends the inclusion of SmartView 1 on new submittals from December 1st, 2024. For assistance transitioning from SmartView 1 to SmartView 2, please contact our sales team at&nbsp;<a href=\"mailto:sales.us@avire-global.com\" target=\"_blank\" rel=\"noreferrer noopener\">sales.us@avire-global.com<\/a>.<\/strong><br><br>RATH\u00ae SmartView 1 provides code-compliant two-way voice and visual text communication for elevator passengers. Designed with a modular display, phone, and camera, this system delivers real-time audible and visual feedback, such as \u201cCall Received\u201d and \u201cHelp Is On the Way,\u201d ensuring all passengers, including those with hearing or speech impairments, can confidently request and receive assistance.<\/p>\n\n\n\n<p>SmartView 1 is ideal for facilities that need a reliable, proven solution that meets ASME and CSA requirements. It integrates easily into a wide range of elevator environments and supports core life safety communication needs without requiring network infrastructure.<\/p>\n<\/div><\/div>\n\t\t\t<\/div>\n\t\t\t<div class=\"wp-block-buttons\">\n\t\t\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group alignfull has-neutral-bg-05-background-color has-background has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\">\n<div class=\"wp-block-doo-block-systems-frame\">\n\t<div class=\"list-systems columns-3 products truncate-description\">\n\t<div class=\"title\">\n\t\t<h2>Our Products<\/h2>\n\t\t\t<\/div>\n\t<div class=\"list-systems-content\">\n\t\t\t\t\t\t\t<div class=\"item product\">\n\t\t\t\t\t\t<div class=\"image\"><img decoding=\"async\" width=\"768\" height=\"465\" src=\"https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2023\/10\/2100-SVC-768x465.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"SmartView Controller 2100-SVC\" srcset=\"https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2023\/10\/2100-SVC-768x465.png 768w, https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2023\/10\/2100-SVC-300x182.png 300w, https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2023\/10\/2100-SVC.png 974w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div>\n\t\t\t\t\t\t<div class=\"content\">\n\t\t\t\t\t\t\t<div class=\"text\">\n\t\t\t\t\t\t\t\t<div class=\"title title-color\">SmartView Controller 2100-SVC<\/div>\n\t\t\t\t\t\t\t\t<div class=\"description\">The 2100-SVC SmartView Controller is the brains of the system that connects the software, display, buttons, and camera for a fully functional system.\r\nThe board is affixed to a mounting plate.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"bottom\">\n\t\t\t\t\t\t\t\t<div class=\"doo-link\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.avire-global.com\/en-us\/product\/elevator-two-way-visual-communication\/smartview-controller-2100-svc\/\">See product<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<!-- <div class=\"brands\"><img decoding=\"async\" width=\"300\" height=\"111\" src=\"https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2025\/11\/RATH-logo_full-color_no-background.svg\" class=\"attachment-medium size-medium\" alt=\"Rath\" \/><\/div> -->\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"item product\">\n\t\t\t\t\t\t<div class=\"image\"><img decoding=\"async\" width=\"768\" height=\"465\" src=\"https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2023\/09\/2100-SVD-Display-1-768x465.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"2100-SVD-Display\" srcset=\"https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2023\/09\/2100-SVD-Display-1-768x465.png 768w, https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2023\/09\/2100-SVD-Display-1-300x182.png 300w, https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2023\/09\/2100-SVD-Display-1.png 974w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div>\n\t\t\t\t\t\t<div class=\"content\">\n\t\t\t\t\t\t\t<div class=\"text\">\n\t\t\t\t\t\t\t\t<div class=\"title title-color\">SmartView Display 2100-SVD<\/div>\n\t\t\t\t\t\t\t\t<div class=\"description\">The 2100-SVD SmartView Display integrates with the SmartView Controller. It displays 5\/16&#8243; text from a call center on a 5&#8243; screen.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"bottom\">\n\t\t\t\t\t\t\t\t<div class=\"doo-link\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.avire-global.com\/en-us\/product\/elevator-two-way-visual-communication\/smartview-display-2100-svd\/\">See product<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<!-- <div class=\"brands\"><img decoding=\"async\" width=\"300\" height=\"111\" src=\"https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2025\/11\/RATH-logo_full-color_no-background.svg\" class=\"attachment-medium size-medium\" alt=\"Rath\" \/><\/div> -->\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"item product\">\n\t\t\t\t\t\t<div class=\"image\"><img decoding=\"async\" width=\"768\" height=\"465\" src=\"https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2023\/10\/SmartView-Ethernet-Extenders-2100-SVE-768x465.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"SmartView-Ethernet-Extenders-2100-SVE\" srcset=\"https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2023\/10\/SmartView-Ethernet-Extenders-2100-SVE-768x465.png 768w, https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2023\/10\/SmartView-Ethernet-Extenders-2100-SVE-300x182.png 300w, https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2023\/10\/SmartView-Ethernet-Extenders-2100-SVE.png 974w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div>\n\t\t\t\t\t\t<div class=\"content\">\n\t\t\t\t\t\t\t<div class=\"text\">\n\t\t\t\t\t\t\t\t<div class=\"title title-color\">SmartView Ethernet Extenders 2100-SVE<\/div>\n\t\t\t\t\t\t\t\t<div class=\"description\">The 2100-SVE SmartView Ethernet Extenders supplies an extra 1A to the SmartView Controller. It extends over 1-pair of wiring.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"bottom\">\n\t\t\t\t\t\t\t\t<div class=\"doo-link\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.avire-global.com\/en-us\/product\/elevator-two-way-visual-communication\/smartview-ethernet-extenders-2100-sve\/\">See product<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<!-- <div class=\"brands\"><img decoding=\"async\" width=\"300\" height=\"111\" src=\"https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2025\/11\/RATH-logo_full-color_no-background.svg\" class=\"attachment-medium size-medium\" alt=\"Rath\" \/><\/div> -->\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"item product\">\n\t\t\t\t\t\t<div class=\"image\"><img decoding=\"async\" width=\"600\" height=\"417\" src=\"https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2023\/11\/2100-SVCF-_shadowed.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"2100-SVCF\" srcset=\"https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2023\/11\/2100-SVCF-_shadowed.png 600w, https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2023\/11\/2100-SVCF-_shadowed-300x209.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/div>\n\t\t\t\t\t\t<div class=\"content\">\n\t\t\t\t\t\t\t<div class=\"text\">\n\t\t\t\t\t\t\t\t<div class=\"title title-color\">2100-SVCF (Elevator Camera)<\/div>\n\t\t\t\t\t\t\t\t<div class=\"description\">The RATH\u00ae 2100-SVCF Panel Mount Elevator Camera provides clear video for elevator emergency communication as part of the SmartView 2 system. Designed for seamless integration into elevator panels, it enables visual monitoring to support communication between passengers and responders during emergency situations.\n \nWith a compact, panel-mount design and durable stainless steel construction, the camera installs cleanly into elevator fixtures while maintaining long-term performance. Optimized for SmartView 2 systems, it delivers a reliable solution for enabling visual communication in modern elevator environments.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"bottom\">\n\t\t\t\t\t\t\t\t<div class=\"doo-link\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.avire-global.com\/en-us\/product\/smartview-2-two-way-visual-communication\/smartview-behind-the-panel-camera-2100-svcf\/\">See product<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<!-- <div class=\"brands\"><img decoding=\"async\" width=\"300\" height=\"111\" src=\"https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2025\/11\/RATH-logo_full-color_no-background.svg\" class=\"attachment-medium size-medium\" alt=\"Rath\" \/><\/div> -->\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"item product\">\n\t\t\t\t\t\t<div class=\"image\"><img decoding=\"async\" width=\"600\" height=\"487\" src=\"https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2023\/11\/2100-SVCF-CM-_shadowed.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"2100-SVCF-CM\" srcset=\"https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2023\/11\/2100-SVCF-CM-_shadowed.png 600w, https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2023\/11\/2100-SVCF-CM-_shadowed-300x244.png 300w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/div>\n\t\t\t\t\t\t<div class=\"content\">\n\t\t\t\t\t\t\t<div class=\"text\">\n\t\t\t\t\t\t\t\t<div class=\"title title-color\">2100-SVCF-CM (Elevator Camera)<\/div>\n\t\t\t\t\t\t\t\t<div class=\"description\">The RATH\u00ae 2100-SVCF-CM Corner Mount Elevator Camera provides flexible video coverage for elevator emergency communication as part of the SmartView 2 system. Designed for corner-mounted installation, it enables optimal camera placement in elevator cabs where panel mounting is not practical or desired.\n \nWith a durable stainless steel enclosure and integrated mounting bracket, the camera delivers reliable performance in demanding environments while maintaining a clean, professional appearance. Optimized for SmartView 2 systems, it provides a dependable solution for enabling visual communication in a wide range of elevator installations.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"bottom\">\n\t\t\t\t\t\t\t\t<div class=\"doo-link\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.avire-global.com\/en-us\/product\/smartview-2-two-way-visual-communication\/smartview-corner-mount-camera-2100-svcf-cm\/\">See product<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<!-- <div class=\"brands\"><img decoding=\"async\" width=\"300\" height=\"111\" src=\"https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2025\/11\/RATH-logo_full-color_no-background.svg\" class=\"attachment-medium size-medium\" alt=\"Rath\" \/><\/div> -->\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"item product\">\n\t\t\t\t\t\t<div class=\"image\"><img decoding=\"async\" width=\"768\" height=\"465\" src=\"https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2023\/10\/2100-SVSCOMP-768x465.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"2100-SVSCOMP\" srcset=\"https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2023\/10\/2100-SVSCOMP-768x465.png 768w, https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2023\/10\/2100-SVSCOMP-300x182.png 300w, https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2023\/10\/2100-SVSCOMP.png 974w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div>\n\t\t\t\t\t\t<div class=\"content\">\n\t\t\t\t\t\t\t<div class=\"text\">\n\t\t\t\t\t\t\t\t<div class=\"title title-color\">SmartView Field Mod Complete Systems<\/div>\n\t\t\t\t\t\t\t\t<div class=\"description\">The SmartView is offered as a complete system for Field Mod projects that includes the SmartView controller, camera, display, and YES and NO buttons.\r\nIt is compatible with the SmartView Software. Choose a flush or surface mount option.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"bottom\">\n\t\t\t\t\t\t\t\t<div class=\"doo-link\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.avire-global.com\/en-us\/product\/elevator-two-way-visual-communication\/smartview-field-mod-complete-systems\/\">See product<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<!-- <div class=\"brands\"><img decoding=\"async\" width=\"300\" height=\"111\" src=\"https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2025\/11\/RATH-logo_full-color_no-background.svg\" class=\"attachment-medium size-medium\" alt=\"Rath\" \/><\/div> -->\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<div class=\"item product\">\n\t\t\t\t\t\t<div class=\"image\"><img decoding=\"async\" width=\"768\" height=\"465\" src=\"https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2023\/10\/IP-Command-Center-Power-Supplies-768x465.png\" class=\"attachment-medium_large size-medium_large wp-post-image\" alt=\"IP-Command-Center-Power-Supplies\" srcset=\"https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2023\/10\/IP-Command-Center-Power-Supplies-768x465.png 768w, https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2023\/10\/IP-Command-Center-Power-Supplies-300x182.png 300w, https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2023\/10\/IP-Command-Center-Power-Supplies.png 974w\" sizes=\"(max-width: 768px) 100vw, 768px\" \/><\/div>\n\t\t\t\t\t\t<div class=\"content\">\n\t\t\t\t\t\t\t<div class=\"text\">\n\t\t\t\t\t\t\t\t<div class=\"title title-color\">SmartView 1 Uninterruptible Power Supply (UPS)<\/div>\n\t\t\t\t\t\t\t\t<div class=\"description\">Designed to meet essential backup requirements, the RP7700104S Uninterruptible Power Supply keeps the SmartView system running when the power goes out during an emergency.<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<div class=\"bottom\">\n\t\t\t\t\t\t\t\t<div class=\"doo-link\">\n\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.avire-global.com\/en-us\/product\/elevator-two-way-visual-communication\/smartview-uninterruptible-power-supply-ups\/\">See product<\/a>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<!-- <div class=\"brands\"><img decoding=\"async\" width=\"300\" height=\"111\" src=\"https:\/\/www.avire-global.com\/en-us\/wp-content\/uploads\/sites\/10\/2025\/11\/RATH-logo_full-color_no-background.svg\" class=\"attachment-medium size-medium\" alt=\"Rath\" \/><\/div> -->\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<div class=\"wp-block-group has-global-padding is-layout-constrained wp-block-group-is-layout-constrained\" style=\"padding-top:var(--wp--preset--spacing--fluid-32-72);padding-bottom:var(--wp--preset--spacing--fluid-32-72)\">\n<div class=\"block-support-container cards-count-4 wp-block-doo-block-block-support\">\n\t<div class=\"block-support-wrapper\">\n\t\t<div class=\"block-support-content\">\n\t\t\t<div class=\"block-support-text\">\n\t\t\t\t\t\t\t\t\t<h2 class=\"block-support-header\">Education, Training &amp; Support<\/h2>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"block-support-paragraph\">We believe that ongoing education is paramount to your professional development.\u2028\u2028<br>As the code and training experts, our website offers all the documentation and educational resources needed to assist you in making the right decisions.<\/p>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\n\t\t\t\t\t\t\t<div class=\"block-support-cards\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"block-support-card\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"block-support-card-title\">Education<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"block-support-card-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"block-support-card-description\">Whether you&#8217;re looking to build your knowledge, troubleshoot an issue, or connect with a product expert \u2013 were here to help! Access the tools and support you need to make informed, code-compliant decisions.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.avire-global.com\/en-us\/learning\/\" class=\"block-support-card-link\">\n\t\t\t\t\t\t\t\t\t\t\tSee Education\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"block-support-card\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"block-support-card-title\">FAQs<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"block-support-card-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"block-support-card-description\">Get quick answers to common questions.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.avire-global.com\/en-us\/faqs\/\" class=\"block-support-card-link\">\n\t\t\t\t\t\t\t\t\t\t\tSee FAQs\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"block-support-card\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"block-support-card-title\">Technical Support<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"block-support-card-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"block-support-card-description\">Schedule time with a support specialist.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.avire-global.com\/en-us\/contact\/#tech-support\" class=\"block-support-card-link\">\n\t\t\t\t\t\t\t\t\t\t\tTechnical Support\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"block-support-card\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<h3 class=\"block-support-card-title\">Contact Sales<\/h3>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<div class=\"block-support-card-content\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<p class=\"block-support-card-description\">Speak with a sales expert about your project needs.<\/p>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/www.avire-global.com\/en-us\/contact\/#sales\" class=\"block-support-card-link\">\n\t\t\t\t\t\t\t\t\t\t\tContact Sales\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t<\/div>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":12461,"parent":9962,"menu_order":0,"template":"","meta":{"_eb_attr":"","inline_featured_image":false,"doo-cf-term":147,"doo-cf-codes":null,"footnotes":""},"brand":[38],"class_list":["post-11104","division","type-division","status-publish","has-post-thumbnail","hentry","brand-rath"],"_links":{"self":[{"href":"https:\/\/www.avire-global.com\/en-us\/wp-json\/wp\/v2\/division\/11104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.avire-global.com\/en-us\/wp-json\/wp\/v2\/division"}],"about":[{"href":"https:\/\/www.avire-global.com\/en-us\/wp-json\/wp\/v2\/types\/division"}],"version-history":[{"count":5,"href":"https:\/\/www.avire-global.com\/en-us\/wp-json\/wp\/v2\/division\/11104\/revisions"}],"predecessor-version":[{"id":12914,"href":"https:\/\/www.avire-global.com\/en-us\/wp-json\/wp\/v2\/division\/11104\/revisions\/12914"}],"up":[{"embeddable":true,"href":"https:\/\/www.avire-global.com\/en-us\/wp-json\/wp\/v2\/division\/9962"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.avire-global.com\/en-us\/wp-json\/wp\/v2\/media\/12461"}],"wp:attachment":[{"href":"https:\/\/www.avire-global.com\/en-us\/wp-json\/wp\/v2\/media?parent=11104"}],"wp:term":[{"taxonomy":"brand","embeddable":true,"href":"https:\/\/www.avire-global.com\/en-us\/wp-json\/wp\/v2\/brand?post=11104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}